{"id":8618,"date":"2026-07-15T06:50:50","date_gmt":"2026-07-15T06:50:50","guid":{"rendered":"https:\/\/lavozdedelicias.com\/?p=8618"},"modified":"2026-07-15T06:50:50","modified_gmt":"2026-07-15T06:50:50","slug":"gobierno-interino-de-venezuela-y-oposicion-iniciaran-mesa-de-trabajo-el-1-de-agosto","status":"publish","type":"post","link":"https:\/\/lavozdedelicias.com\/index.php\/2026\/07\/15\/gobierno-interino-de-venezuela-y-oposicion-iniciaran-mesa-de-trabajo-el-1-de-agosto\/","title":{"rendered":"Gobierno interino de Venezuela y oposici\u00f3n iniciar\u00e1n mesa de trabajo el 1 de agosto"},"content":{"rendered":"<p>El\u00a0Gobierno interino de Venezuela\u00a0anunci\u00f3 que\u00a0a partir del 1 de agosto\u00a0iniciar\u00e1 una\u00a0hoja de trabajo\u00a0con integrantes de la\u00a0oposici\u00f3n, como parte de un proceso para fortalecer las instituciones democr\u00e1ticas del pa\u00eds. El anuncio fue realizado por el\u00a0presidente de la Asamblea Nacional,\u00a0Jorge Rodr\u00edguez, siete meses despu\u00e9s de la\u00a0salida del poder de Nicol\u00e1s Maduro, seg\u00fan inform\u00f3 el Parlamento venezolano.<\/p>\n<p>La decisi\u00f3n se dio tras la visita a\u00a0Caracas\u00a0de\u00a0Dinorah Figuera, quien encabeza la comisi\u00f3n que representa a la\u00a0Asamblea Nacional 2015-2020, \u00f3rgano reconocido por\u00a0Estados Unidos\u00a0como el\u00a0Legislativo leg\u00edtimo de Venezuela. Durante su estancia sostuvo reuniones con representantes del\u00a0Gobierno\u00a0y\u00a0dirigentes opositores.<\/p>\n<h2 id=\"h-que-contempla-la-hoja-de-trabajo-entre-el-gobierno-y-la-oposicion\" class=\"wp-block-heading\">\u00bfQu\u00e9 contempla la hoja de trabajo entre el Gobierno y la oposici\u00f3n?<\/h2>\n<div class=\"code-block code-block-1\"><\/div>\n<p>En un comunicado, Jorge Rodr\u00edguez inform\u00f3 que el objetivo es avanzar en una agenda conjunta para fortalecer la democracia.<\/p>\n<p>Por su parte,\u00a0Dinorah Figuera\u00a0asegur\u00f3 que existe la voluntad pol\u00edtica para impulsar una ruta t\u00e9cnica y pol\u00edtica que permita avanzar hacia la recuperaci\u00f3n democr\u00e1tica del pa\u00eds.<\/p>\n<p>De acuerdo con un comunicado difundido por los exparlamentarios opositores, los temas prioritarios ser\u00e1n:<\/p>\n<ul class=\"wp-block-list\">\n<li>Fortalecimiento de las instituciones democr\u00e1ticas<\/li>\n<li>Mejoras al sistema electoral<\/li>\n<li>Restablecimiento de las garant\u00edas para la participaci\u00f3n pol\u00edtica<\/li>\n<\/ul>\n<h2 id=\"h-el-parlamento-reanuda-actividades-tras-los-sismos\" class=\"wp-block-heading\">El Parlamento reanuda actividades tras los sismos<\/h2>\n<p>La\u00a0Asamblea Nacional\u00a0retom\u00f3 sus sesiones en una sede alterna debido a los da\u00f1os que sufri\u00f3 el\u00a0Palacio Legislativo\u00a0tras los\u00a0sismos del 24 de junio.<\/p>\n<div class=\"code-block code-block-18\"><\/div>\n<p>Durante la sesi\u00f3n,\u00a0Jorge Rodr\u00edguez\u00a0confirm\u00f3 el fallecimiento de la diputada\u00a0Jessica Carolina de Le\u00f3n\u00a0y de su hija como consecuencia del desastre.<\/p>\n<h2 id=\"h-maria-corina-machado-mantiene-su-postura-sobre-nuevas-elecciones\" class=\"wp-block-heading\">Mar\u00eda Corina Machado mantiene su postura sobre nuevas elecciones<\/h2>\n<p>La l\u00edder opositora\u00a0Mar\u00eda Corina Machado, quien permanece en el exilio, no se pronunci\u00f3 sobre el acercamiento encabezado por Dinorah Figuera.<\/p>\n<p>Machado contin\u00faa defendiendo la celebraci\u00f3n de\u00a0nuevas elecciones presidenciales\u00a0y previamente manifest\u00f3 su disposici\u00f3n para negociar una transici\u00f3n democr\u00e1tica con el Gobierno interino.<\/p>\n<p>Desde que\u00a0Delcy Rodr\u00edguez\u00a0asumi\u00f3 la Presidencia interina en enero, su administraci\u00f3n ha liberado a parte de los\u00a0presos pol\u00edticos, impulsado reformas para atraer inversi\u00f3n extranjera y restablecido las relaciones diplom\u00e1ticas y consulares con\u00a0Estados Unidos, adem\u00e1s de realizar cambios recientes en su\u00a0gabinete.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8619\" src=\"https:\/\/lavozdedelicias.com\/wp-content\/uploads\/2026\/07\/afp-presidenta-interina-venezuela-161248-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/lavozdedelicias.com\/wp-content\/uploads\/2026\/07\/afp-presidenta-interina-venezuela-161248-300x169.jpg 300w, https:\/\/lavozdedelicias.com\/wp-content\/uploads\/2026\/07\/afp-presidenta-interina-venezuela-161248-1024x576.jpg 1024w, https:\/\/lavozdedelicias.com\/wp-content\/uploads\/2026\/07\/afp-presidenta-interina-venezuela-161248-768x432.jpg 768w, https:\/\/lavozdedelicias.com\/wp-content\/uploads\/2026\/07\/afp-presidenta-interina-venezuela-161248-390x220.jpg 390w, https:\/\/lavozdedelicias.com\/wp-content\/uploads\/2026\/07\/afp-presidenta-interina-venezuela-161248.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0Gobierno interino de Venezuela\u00a0anunci\u00f3 que\u00a0a partir del 1 de agosto\u00a0iniciar\u00e1 una\u00a0hoja de trabajo\u00a0con integrantes de la\u00a0oposici\u00f3n, como parte de un proceso para fortalecer las instituciones democr\u00e1ticas del pa\u00eds. El anuncio fue realizado por el\u00a0presidente de la Asamblea Nacional,\u00a0Jorge Rodr\u00edguez, siete meses despu\u00e9s de la\u00a0salida del poder de Nicol\u00e1s Maduro, seg\u00fan inform\u00f3 el Parlamento venezolano. La &hellip;<\/p>\n","protected":false},"author":2,"featured_media":8619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-8618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/posts\/8618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/comments?post=8618"}],"version-history":[{"count":1,"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/posts\/8618\/revisions"}],"predecessor-version":[{"id":8620,"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/posts\/8618\/revisions\/8620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/media\/8619"}],"wp:attachment":[{"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/media?parent=8618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/categories?post=8618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdedelicias.com\/index.php\/wp-json\/wp\/v2\/tags?post=8618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}